{"id":10000102,"date":"2025-02-04T01:03:48","date_gmt":"2025-02-03T23:03:48","guid":{"rendered":"https:\/\/www.starcitizen.lt\/?post_type=tribe_events&#038;p=8836"},"modified":"2025-02-04T01:03:48","modified_gmt":"2025-02-03T23:03:48","slug":"visuotinis-sekmadienio-susirinkimas-star-citizen-lietuva-3","status":"publish","type":"tribe_events","link":"https:\/\/www.starcitizen.lt\/lt\/event\/visuotinis-sekmadienio-susirinkimas-star-citizen-lietuva-3\/2026-11-15\/","title":{"rendered":"Visuotinis sekmadienio susirinkimas Star Citizen Lietuva"},"content":{"rendered":"<h1>Visuotinis sekmadienio susirinkimas<\/h1>\n<ul>\n<li>Prisistatymas<\/li>\n<li>Naujienos<\/li>\n<li>Atvira diskusij\u0105<\/li>\n<\/ul>\n<p>https:\/\/discord.com\/channels\/1092896929895153766\/1331280159705137203<br \/>\nhttp:\/\/www.discord.gg\/sC5xpwpJQ4<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Visuotinis sekmadienio susirinkimas Prisistatymas Naujienos Atvira diskusij\u0105 https:\/\/discord.com\/channels\/1092896929895153766\/1331280159705137203 http:\/\/www.discord.gg\/sC5xpwpJQ4<\/p>\n","protected":false},"author":3,"featured_media":8839,"comment_status":"open","ping_status":"closed","template":"","meta":{"_tec_requires_first_save":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_EventAllDay":false,"_EventTimezone":"Europe\/Vilnius","_EventStartDate":"2026-11-15 21:00:00","_EventEndDate":"2026-11-15 22:00:00","_EventStartDateUTC":"2026-11-15 19:00:00","_EventEndDateUTC":"2026-11-15 20:00:00","_EventShowMap":true,"_EventShowMapLink":true,"_EventURL":"https:\/\/discord.com\/channels\/1092896929895153766\/1331280159705137203","_EventCost":"0","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[7162],"_EventVenueID":[7160],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_blocks_recurrence_rules":"[{\"all_day\":false,\"multi_day\":false,\"type\":\"weekly\",\"limit_type\":\"never\",\"limit\":false,\"between\":1,\"start_time\":\"21:00:00\",\"end_time\":\"22:00:00\",\"days\":[7],\"isOffStart\":false}]","_tribe_blocks_recurrence_description":"","_tribe_blocks_recurrence_exclusions":"","_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[33],"tribe_events_cat":[103],"class_list":["post-10000102","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-susitikimas","tribe_events_cat-hebros-susiburimas","cat_hebros-susiburimas","tribe-recurring-event","tribe-recurring-event-parent"],"aioseo_notices":[],"ticketed":false,"_links":{"self":[{"href":"https:\/\/www.starcitizen.lt\/lt\/wp-json\/wp\/v2\/tribe_events\/10000102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.starcitizen.lt\/lt\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.starcitizen.lt\/lt\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.starcitizen.lt\/lt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.starcitizen.lt\/lt\/wp-json\/wp\/v2\/comments?post=10000102"}],"version-history":[{"count":0,"href":"https:\/\/www.starcitizen.lt\/lt\/wp-json\/wp\/v2\/tribe_events\/10000102\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.starcitizen.lt\/lt\/wp-json\/wp\/v2\/media\/8839"}],"wp:attachment":[{"href":"https:\/\/www.starcitizen.lt\/lt\/wp-json\/wp\/v2\/media?parent=10000102"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.starcitizen.lt\/lt\/wp-json\/wp\/v2\/tags?post=10000102"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.starcitizen.lt\/lt\/wp-json\/wp\/v2\/tribe_events_cat?post=10000102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}